{"id":10270,"date":"2024-12-22T09:31:33","date_gmt":"2024-12-22T08:31:33","guid":{"rendered":"https:\/\/lettresdepoilus-pays-de-ploermel.fr\/?p=10270"},"modified":"2024-12-22T09:31:33","modified_gmt":"2024-12-22T08:31:33","slug":"joseph-tempier","status":"publish","type":"post","link":"https:\/\/lettresdepoilus-pays-de-ploermel.fr\/index.php\/2024\/12\/22\/joseph-tempier\/","title":{"rendered":"Joseph TEMPIER"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Joseph Victor TEMPIER est n\u00e9 le 13 mars 1891 \u00e0 Mohon (Morbihan) et est d\u00e9c\u00e9d\u00e9 le 4 mars 1915 \u00e0 Notre Dame de Lorette (Pas de Calais) &#8211; Notre-Dame-de-Lorette est une colline sur le territoire de la commune d&rsquo;Ablain-Saint-Nazaire pr\u00e8s d&rsquo;Arras.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il \u00e9tait incorpor\u00e9 au 1er bataillon Chasseurs.  <\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img fetchpriority=\"high\" decoding=\"async\" width=\"293\" height=\"311\" src=\"https:\/\/lettresdepoilus-pays-de-ploermel.fr\/wp-content\/uploads\/2024\/12\/image-8.png\" alt=\"\" class=\"wp-image-10436\" style=\"width:238px;height:auto\" srcset=\"https:\/\/lettresdepoilus-pays-de-ploermel.fr\/wp-content\/uploads\/2024\/12\/image-8.png 293w, https:\/\/lettresdepoilus-pays-de-ploermel.fr\/wp-content\/uploads\/2024\/12\/image-8-283x300.png 283w\" sizes=\"(max-width: 293px) 100vw, 293px\" \/><\/figure>\n<\/div>\n\n\n<div style=\"height:14px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div data-wp-interactive=\"core\/file\" class=\"wp-block-file\"><object data-wp-bind--hidden=\"!state.hasPdfPreview\" hidden class=\"wp-block-file__embed\" data=\"https:\/\/lettresdepoilus-pays-de-ploermel.fr\/wp-content\/uploads\/2024\/12\/Historique_du_1er_bataillon_de_._bpt6k63363049-1.pdf\" type=\"application\/pdf\" style=\"width:100%;height:600px\" aria-label=\"Contenu embarqu\u00e9 Historique_du_1er_bataillon_de_[...]_bpt6k63363049 (1).\"><\/object><a id=\"wp-block-file--media-3934323b-783e-4738-a17f-f8d40dc43064\" href=\"https:\/\/lettresdepoilus-pays-de-ploermel.fr\/wp-content\/uploads\/2024\/12\/Historique_du_1er_bataillon_de_._bpt6k63363049-1.pdf\">Historique_du_1er_bataillon_de_[&#8230;]_bpt6k63363049 (1)<\/a><a href=\"https:\/\/lettresdepoilus-pays-de-ploermel.fr\/wp-content\/uploads\/2024\/12\/Historique_du_1er_bataillon_de_._bpt6k63363049-1.pdf\" class=\"wp-block-file__button wp-element-button\" download aria-describedby=\"wp-block-file--media-3934323b-783e-4738-a17f-f8d40dc43064\">T\u00e9l\u00e9charger<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Joseph Victor TEMPIER est n\u00e9 le 13 mars 1891 \u00e0 Mohon (Morbihan) et est d\u00e9c\u00e9d\u00e9 le 4 mars 1915 \u00e0 Notre Dame de Lorette (Pas de Calais) &#8211; Notre-Dame-de-Lorette est une colline sur le territoire de la commune d&rsquo;Ablain-Saint-Nazaire pr\u00e8s d&rsquo;Arras. Il \u00e9tait incorpor\u00e9 au 1er bataillon Chasseurs.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"iawp_total_views":1,"footnotes":""},"categories":[45],"tags":[75],"class_list":["post-10270","post","type-post","status-publish","format-standard","hentry","category--portraits","tag-mohon"],"acf":[],"_links":{"self":[{"href":"https:\/\/lettresdepoilus-pays-de-ploermel.fr\/index.php\/wp-json\/wp\/v2\/posts\/10270","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lettresdepoilus-pays-de-ploermel.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lettresdepoilus-pays-de-ploermel.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lettresdepoilus-pays-de-ploermel.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lettresdepoilus-pays-de-ploermel.fr\/index.php\/wp-json\/wp\/v2\/comments?post=10270"}],"version-history":[{"count":3,"href":"https:\/\/lettresdepoilus-pays-de-ploermel.fr\/index.php\/wp-json\/wp\/v2\/posts\/10270\/revisions"}],"predecessor-version":[{"id":10437,"href":"https:\/\/lettresdepoilus-pays-de-ploermel.fr\/index.php\/wp-json\/wp\/v2\/posts\/10270\/revisions\/10437"}],"wp:attachment":[{"href":"https:\/\/lettresdepoilus-pays-de-ploermel.fr\/index.php\/wp-json\/wp\/v2\/media?parent=10270"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lettresdepoilus-pays-de-ploermel.fr\/index.php\/wp-json\/wp\/v2\/categories?post=10270"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lettresdepoilus-pays-de-ploermel.fr\/index.php\/wp-json\/wp\/v2\/tags?post=10270"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}